{"id":1042,"date":"2026-03-23T15:22:10","date_gmt":"2026-03-23T14:22:10","guid":{"rendered":"https:\/\/lapieceur.com\/site26\/?p=1042"},"modified":"2026-04-13T16:39:56","modified_gmt":"2026-04-13T14:39:56","slug":"paolo-costume-2-pieces-sur-mesure-en-toile-de-laine-nattee-turquoise","status":"publish","type":"post","link":"https:\/\/lapieceur.com\/site26\/paolo-costume-2-pieces-sur-mesure-en-toile-de-laine-nattee-turquoise\/","title":{"rendered":"PAOLO &#8211; Costume 2 pi\u00e8ces sur mesure en Toile de laine natt\u00e9e turquoise"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section preset--group--divi-section--divi-spacing--default\">\n<div class=\"et_pb_row_0 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_0 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_3_5 et_flex_column_3_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_3_5_tabletWide preset--group--divi-column--divi-spacing--default\">\n\n\n\n\n<div class=\"et_pb_module et_d4_element lwp_divi_breadcrumbs lwp_divi_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"lwp-breadcrumbs\"> <span class=\"before\"><\/span> <span vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" href=\"https:\/\/lapieceur.com\/site26\/costume-mariage-sur-mesure\/\" class=\"home\"><span property=\"name\">Mariage sur mesure<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> <span class=\"separator et-pb-icon\">5<\/span> <\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\n\n\n<\/div>\n\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough et_flex_column_2_5 et_flex_column_2_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_2_5_tabletWide preset--group--divi-column--divi-spacing--default\"><\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_2 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_3_5 et_flex_column_3_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_3_5_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-spacing--default preset--group--divi-text--divi-font-body--default preset--group--divi-text--divi-font-header--default\"><div class=\"et_pb_text_inner\"><h1>PAOLO<\/h1>\n<\/div><\/div>\n\n<div class=\"et_pb_image_0 et_pb_image et_pb_image_sticky et_pb_module et_flex_module preset--group--divi-image--divi-spacing--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3.webp\" title=\"Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3\" width=\"1440\" height=\"2160\" srcset=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3.webp 1440w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3-1280x1920.webp 1280w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3-980x1470.webp 980w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3-480x720.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1440px, 100vw\" class=\"wp-image-2418\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_2_5 et_flex_column_2_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_2_5_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-spacing--default preset--group--divi-text--divi-font-body--default preset--group--divi-text--divi-font-header--default\"><div class=\"et_pb_text_inner\"><h3>Toile de laine natt\u00e9e turquoise, 100% laine, poids 240gr\/mt<\/h3>\n<p>Costume 2 pi\u00e8ces sur mesure avec une veste \u00e0 col ch\u00e2le, 1 bouton et 3 poches en biais passepoil\u00e9es.<br \/>\u2013 1040&nbsp;\u20ac<\/p>\n<p>Chemise blanche sur mesure en popeline de coton.<br \/>\u2013 140&nbsp;\u20ac<\/p>\n<h5><a href=\"https:\/\/lapieceur.com\/site26\/prendre-rendez-vous\/\">Rendez-vous en boutique pour essayer le mod\u00e8le Paolo &gt;<\/a><\/h5>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_4 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_3_5 et_flex_column_3_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_3_5_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_video_0 et_pb_video et_pb_module et_flex_module rc-video-autoplay preset--group--divi-video--divi-spacing--default\"><div class=\"et_pb_video_box\"><video controls><source type=\"video\/mp4\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/03\/W25-beauford-video.mp4\" \/><\/video><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_5 et_pb_column et-last-child et_flex_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough et_flex_column_2_5 et_flex_column_2_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_2_5_tabletWide preset--group--divi-column--divi-spacing--default\"><\/div>\n<\/div>\n\n<div class=\"et_pb_row_3 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_6 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_3_5 et_flex_column_3_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_3_5_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_image_1 et_pb_image et_pb_image_sticky et_pb_module et_flex_module preset--group--divi-image--divi-spacing--default\"><a href=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2.webp\" class=\"et_pb_lightbox_image\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2.webp\" title=\"Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2\" width=\"1440\" height=\"2160\" srcset=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2.webp 1440w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2-1280x1920.webp 1280w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2-980x1470.webp 980w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise2-480x720.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1440px, 100vw\" class=\"wp-image-2417\" \/><\/span><\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et-last-child et_flex_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough et_flex_column_2_5 et_flex_column_2_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_2_5_tabletWide preset--group--divi-column--divi-spacing--default\"><\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_8 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_3_5 et_flex_column_3_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_3_5_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_image_2 et_pb_image et_pb_image_sticky et_pb_module et_flex_module preset--group--divi-image--divi-spacing--default\"><a href=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise.webp\" class=\"et_pb_lightbox_image\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise.webp\" title=\"Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise\" width=\"1440\" height=\"2160\" srcset=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise.webp 1440w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise-1280x1920.webp 1280w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise-980x1470.webp 980w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise-480x720.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1440px, 100vw\" class=\"wp-image-2416\" \/><\/span><\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et-last-child et_flex_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough et_flex_column_2_5 et_flex_column_2_5_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_2_5_tabletWide preset--group--divi-column--divi-spacing--default\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section preset--group--divi-section--divi-spacing--default\">\n<div class=\"et_pb_row_5 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_10 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-spacing--default preset--group--divi-text--divi-font-body--default preset--group--divi-text--divi-font-header--default\"><div class=\"et_pb_text_inner\"><h3>Vous aimerez aussi<\/h3>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_6 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\"><div class=\"et_pb_column_11 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide preset--group--divi-column--divi-spacing--default\" data-loop-item=\"0\">\n<div class=\"et_pb_image_3 et_pb_image et_pb_module et_flex_module preset--group--divi-image--divi-spacing--default\"><a href=\"https:\/\/lapieceur.com\/site26\/terry-costume-2-pieces-sur-mesure-en-toile-de-laine-nattee-gris-clair-bleute\/\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Terry-costume-sur-mesure-toile-nattee-gris-bleu-clair-look-book-683x1024.webp\" title=\"Terry-costume-sur-mesure-toile-natt\u00e9e-gris-bleu-clair-look-book\" width=\"683\" height=\"1024\" srcset=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Terry-costume-sur-mesure-toile-nattee-gris-bleu-clair-look-book-683x1024.webp 683w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 683px, 100vw\" class=\"wp-image-2420\" \/><\/span><\/a><\/div>\n<\/div><div class=\"et_pb_column_12 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide preset--group--divi-column--divi-spacing--default\" data-loop-item=\"1\">\n<div class=\"et_pb_image_4 et_pb_image et_pb_module et_flex_module preset--group--divi-image--divi-spacing--default\"><a href=\"https:\/\/lapieceur.com\/site26\/herb-costume-2-pieces-sur-mesure-en-toile-de-laine-nattee-grise-a-carreaux-fenetre-turquoise-et-jaune\/\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux-683x1024.webp\" title=\"Herb-costume-sur-mesure-gris-carreaux\" width=\"683\" height=\"1024\" srcset=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux-683x1024.webp 683w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux-200x300.webp 200w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux-768x1152.webp 768w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux-1024x1536.webp 1024w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux-1365x2048.webp 1365w, https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Herb-costume-sur-mesure-gris-carreaux.webp 1440w\" sizes=\"(max-width: 683px) 100vw, 683px\" class=\"wp-image-2411\" \/><\/span><\/a><\/div>\n<\/div><div class=\"et_pb_column_13 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide preset--group--divi-column--divi-spacing--default\" data-loop-item=\"2\">\n<div class=\"et_pb_image_5 et_pb_image et_pb_module et_flex_module preset--group--divi-image--divi-spacing--default\"><a href=\"https:\/\/lapieceur.com\/site26\/paolo-costume-2-pieces-sur-mesure-en-toile-de-laine-nattee-turquoise\/\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3-683x1024.webp\" title=\"Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3\" width=\"683\" height=\"1024\" srcset=\"https:\/\/lapieceur.com\/site26\/wp-content\/uploads\/2026\/04\/Paolo-costume-sur-mesure-toile-nattee-bleu-turquoise3-683x1024.webp 683w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 683px, 100vw\" class=\"wp-image-2418\" \/><\/span><\/a><\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_row_7 et_pb_row et_flex_row preset--group--divi-row--divi-spacing--default\">\n<div class=\"et_pb_column_14 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_phoneWide et_flex_column_24_24_tabletWide preset--group--divi-column--divi-spacing--default\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-spacing--default preset--group--divi-text--divi-font-body--default preset--group--divi-text--divi-font-header--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><a href=\"https:\/\/lapieceur.com\/site26\/costume-mariage-sur-mesure\/\">Autres collections mariage sur mesure &gt;<\/a><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Costume 2 pi\u00e8ces sur mesure en Toile de laine natt\u00e9e turquoise<\/p>","protected":false},"author":1,"featured_media":2418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[131],"tags":[],"class_list":["post-1042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-standing-figures"],"_links":{"self":[{"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/posts\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":5,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/posts\/1042\/revisions"}],"predecessor-version":[{"id":2435,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/posts\/1042\/revisions\/2435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/media\/2418"}],"wp:attachment":[{"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/categories?post=1042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lapieceur.com\/site26\/wp-json\/wp\/v2\/tags?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}